{"id":104,"date":"2026-03-17T00:16:30","date_gmt":"2026-03-17T00:16:30","guid":{"rendered":"https:\/\/devu4.customdev.solutions\/Bob\/?page_id=104"},"modified":"2026-03-19T22:53:44","modified_gmt":"2026-03-19T22:53:44","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/devu4.customdev.solutions\/Bob\/contact-us\/","title":{"rendered":"Contact Us"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;40&#8243; top_padding_tablet=&#8221;20&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; class=&#8221;man-contaner&#8221; id=&#8221;Connect&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;c1&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;10&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; el_class=&#8221;img1&#8243;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;c2&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; el_class=&#8221;text1 gradiant&#8221; text_direction=&#8221;default&#8221;]\n<h6><span style=\"color: #3b3e77;\">Contacts<\/span><\/h6>\n<h2><span style=\"color: #0d0c0c;\">Have questions?<\/span><br \/>\n<span style=\"color: #0d0c0c;\">Get in touch!<\/span><\/h2>\n<p><span style=\"color: rgba(119, 85, 119, 0.333);\">We\u2019d love to hear from you.<br \/>\nSend us a message using the form below, and we\u2019ll get back to you as soon as we can.<\/span>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;40&#8243; top_padding_tablet=&#8221;20&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; class=&#8221;man-contaner&#8221; id=&#8221;Connect&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;c1&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_raw_html css=&#8221;&#8221;]JTNDaWZyYW1lJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZ3d3cuZ29vZ2xlLmNvbSUyRm1hcHMlMkZlbWJlZCUzRnBiJTNEJTIxMW0xNCUyMTFtOCUyMTFtMyUyMTFkMzI5Ny41NTQyNTUzMTExOTA0JTIxMmQtMTE5LjI0MjY0OCUyMTNkMzQuMjU5OTE2JTIxM20yJTIxMWkxMDI0JTIxMmk3NjglMjE0ZjEzLjElMjEzbTMlMjExbTIlMjExczB4ODBlODUyYjJjMGMwMDEzZCUyNTNBMHgyNWRlYWJmYTdjMjY1Y2RlJTIxMnNWZW50dXJhJTI1MjBDb2xsaXNpb24lMjUyMENlbnRlciUyMTVlMCUyMTNtMiUyMTFzZW4lMjEyc3VzJTIxNHYxNzczOTYwNTcyNDY1JTIxNW0yJTIxMXNlbiUyMTJzdXMlMjIlMjB3aWR0aCUzRCUyMjEwMCUyNSUyMiUyMGhlaWdodCUzRCUyMjQ1MCUyMiUyMHN0eWxlJTNEJTIyYm9yZGVyJTNBMCUzQiUyMiUyMGFsbG93ZnVsbHNjcmVlbiUzRCUyMiUyMiUyMGxvYWRpbmclM0QlMjJsYXp5JTIyJTIwcmVmZXJyZXJwb2xpY3klM0QlMjJuby1yZWZlcnJlci13aGVuLWRvd25ncmFkZSUyMiUzRSUzQyUyRmlmcmFtZSUzRQ==[\/vc_raw_html][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;c2&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; el_class=&#8221;text1 gradiant&#8221; text_direction=&#8221;default&#8221;]\n<h6><span style=\"color: #3b3e77;\">Get in Touch with Our Team<\/span><\/h6>\n<h2><span style=\"color: #0d0c0c;\">We\u2019re here to help.<\/span><\/h2>\n<p><span style=\"color: #000000;\">We\u2019d love to hear from you.<br \/>\nSend us a message using the form below, and we\u2019ll get back to you as soon as we can.<\/span>[\/vc_column_text]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style steadysets-icon-email accent-color\"><\/i> <\/div><div class=\"iwt-text\"> <strong>Email Us:<\/strong><br \/>\n<strong><a href=\"mailto:nick@venturacollisioncenter.net\">nick@venturacollisioncenter.net<\/a><\/strong> <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-phone accent-color\"><\/i> <\/div><div class=\"iwt-text\"> <strong>Call Us:<\/strong><\/p>\n<p><strong><a href=\"tel:18056440994\">+1 805-644-0994<\/a><\/strong> <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style linecon-icon-location accent-color\"><\/i> <\/div><div class=\"iwt-text\"> <strong>Address<\/strong><\/p>\n<p><a href=\"https:\/\/maps.app.goo.gl\/iiu65iRpW8TZadYP7\"><strong>3900 Market Street Ventura CA 93003<\/strong><\/a> <\/div><div class=\"clear\"><\/div><\/div>[nectar_btn size=&#8221;small&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;pop3&#8243; button_id=&#8221;btn_boo&#8221; text=&#8221;Towing Request Form&#8221;][nectar_btn size=&#8221;small&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;pop2&#8243; button_id=&#8221;btn_boo&#8221; text=&#8221;Inquire&#8221;][nectar_btn size=&#8221;small&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;pop1&#8243; button_id=&#8221;btn_boo&#8221; text=&#8221;Accident Information Form&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;40&#8243; top_padding_tablet=&#8221;20&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; class=&#8221;man-contaner&#8221; id=&#8221;Connect&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-104","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/devu4.customdev.solutions\/Bob\/wp-json\/wp\/v2\/pages\/104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devu4.customdev.solutions\/Bob\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/devu4.customdev.solutions\/Bob\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/devu4.customdev.solutions\/Bob\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devu4.customdev.solutions\/Bob\/wp-json\/wp\/v2\/comments?post=104"}],"version-history":[{"count":32,"href":"https:\/\/devu4.customdev.solutions\/Bob\/wp-json\/wp\/v2\/pages\/104\/revisions"}],"predecessor-version":[{"id":297,"href":"https:\/\/devu4.customdev.solutions\/Bob\/wp-json\/wp\/v2\/pages\/104\/revisions\/297"}],"wp:attachment":[{"href":"https:\/\/devu4.customdev.solutions\/Bob\/wp-json\/wp\/v2\/media?parent=104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}